{"id":890,"date":"2015-09-16T12:58:47","date_gmt":"2015-09-16T11:58:47","guid":{"rendered":"http:\/\/www.laiensalvatorianer.at\/spiritual\/?p=890"},"modified":"2015-09-16T12:58:47","modified_gmt":"2015-09-16T11:58:47","slug":"laudato-si-mi-signore-gelobt-seist-du-mein-herr","status":"publish","type":"post","link":"https:\/\/www.laiensalvatorianer.at\/spiritual\/laudato-si-mi-signore-gelobt-seist-du-mein-herr\/","title":{"rendered":"Laudato si\u2019, mi\u2019 Signore \u2013 Gelobt seist du, mein Herr"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;890&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Laudato si\u2019, mi\u2019 Signore \u2013 Gelobt seist du, mein Herr&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\"><a href=\"http:\/\/www.laiensalvatorianer.at\/spiritual\/wp-content\/uploads\/Bayer1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-893\" src=\"http:\/\/www.laiensalvatorianer.at\/spiritual\/wp-content\/uploads\/Bayer1-300x157.jpg\" alt=\"Bayer1\" width=\"300\" height=\"157\" srcset=\"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-content\/uploads\/Bayer1-300x157.jpg 300w, https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-content\/uploads\/Bayer1.jpg 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\"><i>Bayers Bienengifte sind viel gef\u00e4hrlicher als wir lange angenommen haben: <\/i><i>Wissenschaftliche Studien zeigen, dass die sogenannten Neonicotinoide nicht nur Bienen schaden, sondern auch Schmetterlingen, Fischen und V\u00f6geln<\/i><i> &#8212; unser gesamtes \u00d6kosystem ist bedroht.<\/i><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\"><i>Statt die gef\u00e4hrlichen Pestizide endlich aus dem Verkehr zu ziehen, versucht Bayer mit allen Mitteln sein t\u00f6dliches Gesch\u00e4ft zu retten: <\/i><i>Der Chemiekonzern geht soweit gegen ein weitreichendes Verbot der EU Kommission zu klagen.<\/i><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\">Soweit ein Auszug aus einem Text einer Kampagne der NGO \u201eSumOfUs\u201c die sich u.a. f\u00fcr nachhaltige Nutzung unserer G\u00fcter einsetzt. Und was hat das hier zu suchen?<!--more--><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\">Sehr viel, den Papst Franziskus besch\u00e4ftigt sich in seiner Enzyklika \u201eLaudato sii\u201c sehr eingehend mit unserem Umgang mit der Sch\u00f6pfung und in welcher Form wir die Worte der Schrift: \u201eMacht euch die Erde untertan &#8230;\u201c im t\u00e4glichen Handeln auslegen.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\">Im Gegensatz zu andern Schreiben der P\u00e4pste lassen sich hier kaum einzelne S\u00e4tze als kurzes Statement zitieren. Denn sobald man in ein Kapitel eintaucht, wird schnell klar, so einfach ist das nicht \u2013 es sind komplexe Zusammenh\u00e4nge , die sich hier auftun.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\">Aber sie geben auch eine einfache Botschaft: Gehe mit Deiner Umwelt so um, das auch andere Lebewesen neben und mit dir leben k\u00f6nnen. Sieh dich nicht als Herrscher \u00fcber die Welt, sondern trage Verantwortung f\u00fcr Deine N\u00e4chsten, auch wenn dies Pflanzen und Tiere sind, denn sie sind deine unmittelbaren Nachbarn. Ebenso achte die unbelebte Natur und ihre Verteilung, denn sie bildet die Grundlage allen Lebens. Bedenke, dass jeglicher Eingriff Folgen hat, auch wenn sie im Moment nicht sofort erkenntlich sind. Verstehe dich selbst als Verwalter auf der Durchreise, der Verantwortung f\u00fcr kommende Generationen hat \u2013 auch wenn sie nicht deine leiblichen sind.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: book antiqua,palatino,serif; font-size: 12pt;\">Damit liegt in dem Text eine gro\u00dfe Brisanz und ein Auftrag f\u00fcr jeden Menschen. Eben sich auch mit nicht sehr angenehmen Ausw\u00fcchsen unserer Konsum- und Wegwerfgesellschaft auseinander zu setzen, dagegen auf zu stehen, andere dabei zu unterst\u00fctzen, die dies schon tun. Einfach den Glauben und das Vertrauen in Gott umfassend ernst zu nehmen, auch wenn es auf den ersten Blick nicht unmittelbar damit zusammen zu h\u00e4ngen scheint. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bayers Bienengifte sind viel gef\u00e4hrlicher als wir lange angenommen haben: Wissenschaftliche Studien zeigen, dass die sogenannten Neonicotinoide nicht nur Bienen schaden, sondern auch Schmetterlingen, Fischen und V\u00f6geln &#8212; unser gesamtes \u00d6kosystem ist bedroht. Statt die gef\u00e4hrlichen Pestizide endlich aus dem &hellip;<\/p>\n<p><a href=\"https:\/\/www.laiensalvatorianer.at\/spiritual\/laudato-si-mi-signore-gelobt-seist-du-mein-herr\/\">Continue Reading<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4,138,13,5],"tags":[183,157,181,182],"class_list":["post-890","post","type-post","status-publish","format-standard","hentry","category-besinnliches","category-glaube","category-life","category-umwelt","tag-enzyklika","tag-glaube","tag-laudato","tag-umwelt"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/posts\/890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/comments?post=890"}],"version-history":[{"count":4,"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/posts\/890\/revisions"}],"predecessor-version":[{"id":895,"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/posts\/890\/revisions\/895"}],"wp:attachment":[{"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/media?parent=890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/categories?post=890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laiensalvatorianer.at\/spiritual\/wp-json\/wp\/v2\/tags?post=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}